{"id":10120,"date":"2021-02-08T11:59:20","date_gmt":"2021-02-08T11:59:20","guid":{"rendered":"https:\/\/xrei.com\/?p=10120"},"modified":"2021-02-08T15:51:13","modified_gmt":"2021-02-08T15:51:13","slug":"portalegre","status":"publish","type":"post","link":"https:\/\/xrei.com\/it\/portalegre\/","title":{"rendered":"Portalegre, Portogallo"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">In this article, you will get to know about...<\/p>\n<\/div><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/xrei.com\/it\/portalegre\/#Portalegre\" >Portalegre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/xrei.com\/it\/portalegre\/#Luoghi_da_visitare_nella_citta_di_Portalegre\" >Luoghi da visitare nella citt\u00e0 di Portalegre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/xrei.com\/it\/portalegre\/#Altri_luoghi_da_visitare_nel_quartiere_di_Portalegre\" >Altri luoghi da visitare nel quartiere di Portalegre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/xrei.com\/it\/portalegre\/#La_gastronomia_di_Portalegre\" >La gastronomia di Portalegre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/xrei.com\/it\/portalegre\/#Il_mestiere_di_Portalegre\" >Il mestiere di Portalegre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/xrei.com\/it\/portalegre\/#Storia_di_Portalegre\" >Storia di Portalegre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/xrei.com\/it\/portalegre\/#Leconomia_di_Portalegre\" >L&#8217;economia di Portalegre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/xrei.com\/it\/portalegre\/#Posizione_geografica_del_distretto_di_Portalegre\" >Posizione geografica del distretto di Portalegre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/xrei.com\/it\/portalegre\/#Portalegre_Feste_e_Pellegrinaggi\" >Portalegre Feste e Pellegrinaggi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/xrei.com\/it\/portalegre\/#Portalegre_Fast_Facts\" >Portalegre Fast Facts<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Portalegre\"><\/span>Portalegre<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><strong>Portalegre<\/strong> \u00e8 la capitale del distretto con la minor popolazione in Portogallo, situato nel cuore del <strong>Parco Naturale della Serra de S\u00e3o Mamede<\/strong>, nella regione dell&#8217;Alentejo e nella sottoregione dell&#8217;Alentejo. \u00c8 una citt\u00e0 ricca di patrimonio culturale, ovvero con artigianato, costumi, gastronomia, folklore, canti e danze tradizionali. Portalegre attrae il turismo principalmente attraverso la gastronomia e i prodotti alimentari, in particolare con vini, oli d&#8217;oliva, formaggi, salsicce e dolci conventuali. La regione di Portalegre \u00e8 nota per la sua gastronomia, i campi agricoli, la produzione di sughero, i vigneti, l&#8217;artigianato, il bestiame, i formaggi, i dolci conventuali, i castelli nella zona di Raiana del Portogallo, i monumenti romani e l&#8217;archeologia millenaria.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Luoghi_da_visitare_nella_citta_di_Portalegre\"><\/span>Luoghi da visitare nella citt\u00e0 di Portalegre<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3>1. Centro storico della citt\u00e0 di Portalegre<\/h3>\n<p>Il <strong>centro storico di Portalegre<\/strong> \u00e8 un luogo tranquillo pieno di storia, dove possiamo sentire la calma, apprezzare le case dell&#8217;Alentejo, con case bianche e blu mescolate a palazzi signorili. Nelle strade strette e tortuose del centro storico di Portalegre troviamo botteghe tradizionali, e case, con antiche facciate che risalgono al Medioevo.<br \/>\nIl centro di Portalegre \u00e8 organizzato in due aree principali:<\/p>\n<ul>\n<li><strong>Largo do Rossio<\/strong>: dove troviamo il <strong>giardino Avenida Liberdade<\/strong> e il <strong>platano Rossio<\/strong>, un albero piantato nel 1838, \u00e8 attualmente uno degli ex libris di Portalegre, con oltre trenta alto metri, conosciuto come il pi\u00f9 grande platano della penisola iberica.<\/li>\n<li><strong>Pra\u00e7a da Rep\u00fablica<\/strong>: con i portici pieni di terrazze e caff\u00e8, ei palazzi barocchi, dove si trova la Scuola Superiore di Educazione di Portalegre.<\/li>\n<\/ul>\n<h3>2. Serra de S\u00e3o Mamede<\/h3>\n<p><strong>Parco Naturale della Serra de S\u00e3o Mamede<\/strong>: \u00e8 un parco naturale creato nel 1989, che integra i comuni di Arronches, Castelo de Vide, Marv\u00e3o e Portalegre parte della catena montuosa dei <strong>Montes de Toledo<\/strong>. La <strong>Serra de S\u00e3o Mamede<\/strong> \u00e8 la catena montuosa pi\u00f9 alta a sud del fiume Tago, con 1025 metri di altitudine, con <strong>sentieri nella natura<\/strong> di pietra e vegetazione, che collegano piccoli paesi, un luogo di eccellenza per <strong>birdwatching<\/strong>, con una natura che cambia il paesaggio ad ogni stagione. Nella Serra de S\u00e3o Mamede troviamo il <strong>Parco Naturale di S\u00e3o Mamede<\/strong>, un&#8217;area protetta del Portogallo con 56000 ettari distribuiti nei quattro comuni di Portalegre, Castelo de Vide, Marv\u00e3o e Arronches. Il Parco Naturale di S\u00e3o Mamede \u00e8 composto da una vegetazione di sughere, lecci, querce, castagni e pini marittimi, con una bassa vegetazione di cisto. Il <strong>Parco Naturale di S\u00e3o Mamede<\/strong> \u00e8 un&#8217;area di eccellenza per il <strong>birdwatching<\/strong>, in quanto fa parte della <strong>rotta migratoria di molte specie di uccelli tra l&#8217;Europa e l&#8217;Africa<\/strong>, ovvero l&#8217;aquila del Bonelli, Grifone, Avvoltoio nero, Cinghiale dai sopraccigli bianchi, Nibbio bruno, Nibbio reale, Gufo reale, Aquila punta corta, Falco europeo, Gheppio grigio, Pernice, Merlo nero, cinciallegra, cinciallegra, cinciallegra, cinciallegra , ghiandaia comune, stonechat, red robin. Qui vediamo anche lontre, tassi, tori, donnole, gatti selvatici, volpi, conigli selvatici, cinghiali, donnole, lepri, cervi e altri animali selvatici. In alcune parti del parco naturale troviamo colonie di pipistrelli e altri animali anfibi e rettili.<br \/>\nI <strong>quattro principali percorsi a piedi<\/strong> sono il percorso Alegrete con 11 km, il percorso Esperan\u00e7a con 16 km, il percorso Galegos con 11,5 km e il percorso Marv\u00e3o con 8 km.<br \/>\nIl <strong>patrimonio costruito da visitare nella Serra de S\u00e3o Mamede<\/strong>: la diga di P\u00f3voa e Meadas, il Centro per l&#8217;interpretazione dell&#8217;identit\u00e0 locale di Esperan\u00e7a, il castello di Marv\u00e3o, il belvedere di S\u00e3o Mamede, il museo della sinagoga, il museo e la citt\u00e0 romana di Ammaia e le pitture rupestri di Vale de Junco o Lapa dos Gavi\u00f5es.<\/p>\n<ul>\n<li>Il <strong>Pico de S\u00e3o Mamede<\/strong>: situato a circa 1025 metri sul livello del mare, \u00e8 il punto pi\u00f9 alto del Portogallo continentale a sud del Tago. Da qui possiamo godere della vista panoramica sulla diga di Apartadura, il villaggio di Marv\u00e3o, la Serra da Estrela e l&#8217;Estremadura spagnola.<\/li>\n<li><strong>Punto di vista della Cappella di Nossa Senhora da Lapa<\/strong>: \u00e8 una cappella situata a circa 1 km dal villaggio di Besteiros. Merita una menzione speciale per l&#8217;esistenza di una piccola chiesa scavata nella roccia e per la vista che offre sul Parco Naturale della Serra de S\u00e3o Mamede<\/li>\n<\/ul>\n<h3>3. Portalegre Cathedral<\/h3>\n<p><strong>S\u00e9 Catedral de Portalegre<\/strong>: \u00e8 un monumento di architettura rinascimentale del XVI secolo, classificato come monumento nazionale. La S\u00e9 Catedral si distingue per i suoi due campanili, i portali barocchi e le formelle settecentesche che decorano l&#8217;intera sacrestia.<\/p>\n<h3>4. Monastero di S\u00e3o Bernardo<\/h3>\n<p><strong>Monastero di Nossa Senhora da Concei\u00e7\u00e3o de Monjas dell&#8217;Ordine dei Cistercensi<\/strong>: noto come <strong>Convento, o Monastero di S\u00e3o Bernardo<\/strong>, \u00e8 un edificio di architettura manuelina, rinascimentale e barocca classificato come monumento nazionale. Il convento fu inaugurato nel 1518 con lo scopo di accogliere &#8220;fanciulle senza dote&#8221;. Il convento si estinse nel 1878, nel 1911 fu trasformato in caserma, tra il 1932 e il 1961 serv\u00ec da strutture per il <strong>Museo Civico di Portalegre<\/strong>, nei primi anni &#8217;80 serv\u00ec da strutture per la <strong>Scuola Nazionale della Guardia Repubblicana<\/strong>. Le grandi attrazioni del Monastero di S\u00e3o Bernardo sono l&#8217;imponente bellezza del Monastero e il fatto che sia il sito della tomba pi\u00f9 grande e sontuosa del Portogallo, la tomba di D Jorge de Melo, ex Vescovo di Guarda.<br \/>\nIl Convento de S\u00e3o Bernardo \u00e8 conosciuto come uno dei principali conventi dolciari, insieme al Convento di Santa Clara. La pasticceria originaria del Convento di Santa Clara \u00e8 composta dal Toucinho do C\u00e9u, i dolci all&#8217;uovo, il toast francese della badessa, le morcelas dolci di S\u00e3o Bernardo, la torta del convento marcio, il vero torr\u00e3o all&#8217;uovo, il dolce sarrabulho, la zuppa dolce di S\u00e3o Bernardo, e i Pastelli di Pancetta dal cielo.<\/p>\n<h3>5. Convento di Santa Clara<\/h3>\n<p><strong>Convento di Santa Clara<\/strong>: \u00e8 un convento del XIV secolo, fondato dalla regina D Leonor Teles. Il chiostro del convento \u00e8 l&#8217;unico chiostro di architettura fernandina in Portogallo.<br \/>\nIl Convento di Santa Clara \u00e8 conosciuto come uno dei principali conventi dolciari, insieme al Convento di S\u00e3o Bernardo. La pasticceria originaria del Convento di Santa Clara \u00e8 composta dal Golden Cheese, la Marmellata di Mandorle, il Toucinho do C\u00e9u, il Manjar bianco, i Santa Clara Pastels, il Sweet Ham, il Marzapane e la lampreda di mandorle, il Seraph Milk, la Ricetta di abbondanti, la Comfort Cake e i Pasties di mimo.<br \/>\nLa <strong>biblioteca comunale di Portalegre<\/strong> si trova nel Convento di Santa Clara.<\/p>\n<h3>6. Casa-Museo Jos\u00e9 R\u00e9gio<\/h3>\n<p><strong>Casa-Museu Jos\u00e9 R\u00e9gio<\/strong>: \u00e8 un museo installato nella vecchia casa del professore e scrittore Jos\u00e9 Maria dos Reis Pereira, noto come Jos\u00e9 R\u00e9gio. La casa risale alla fine del XVII secolo, dove possiamo visitare le opere e le collezioni di Jos\u00e9 R\u00e9gio, con mostre di scultura, pittura, terracotta, arte religiosa, lavori pastorali e tessuti. Jos\u00e9 R\u00e9gio \u00e8 stato un grande collezionista di arte sacra, arte popolare e artigianato. Le principali attrazioni sono gli oggetti di arte sacra, le immagini di Cristo crocifisso e il Barros de Portalegre.<\/p>\n<h3>7. Portalegre Tapestry Museum Guy Fino<\/h3>\n<p><strong>Portalegre Guy Fino Tapestry Museum<\/strong>: \u00e8 un museo dedicato a Portalegre Tapestry, un arazzo decorativo murale che consiste in una tecnica di arazzo completamente manuale ispirata ad opere originali di pittori, vale a dire replica arazzo di dipinti degli artisti: Almada Negreiros, Anna Christina Dryselius, Ant\u00f3nio Charrua, Ant\u00f3nio DaCosta, Armando Alves, Barbara Walraven, Bruno Munari, Carlos Botelho, Carlos Carreiro, Carlos Santos, Cl\u00e1udia Lima, Costa Pinheiro, Cruzeiro Seixas, Danielle Moser, David Adickes, Eduardo Nery, Em\u00edlia Nadal, Eug\u00e9nio Granell , Figueiredo Sobral, Gilberto Pereira, Gra\u00e7a Morais, Guilherme Camarinha, Joana Vasconcelos, John Olsen, Jorge Martins, Jos\u00e9 de Guimar\u00e3es, Jos\u00e9 Nuno da C\u00e2mara Pereira, Jos\u00e9 Sousa Lara, J\u00falio (Saul Dias), J\u00falio Resende, Lourdes Castro, Lu\u00eds Filipe de Abreu, Lu\u00eds Pinto-Coelho, Manuel Amado, Manuel Cargaleiro, Marcello Moraes, Maria Jo\u00e3o Franco, Mat\u00e9got, Menez, Nadiz Afonso, Otto Nielsen, Paul Mathieu, Renato Torres, Rigo 23, Roger Kathy, Rog\u00e9rio Ribeiro Rui Moreira, S\u00e9rgio Telles, Tom Phillips, Vieira da Silva e Vitor Pomar.<br \/>\nIl Portalegre Guy Fino Tapestry Museum \u00e8 ospitato in un palazzo del XVIII secolo, organizzato al <strong>piano terra<\/strong> con <strong>storia della produzione di arazzi Portalegre<\/strong>, e al <strong>primo piano<\/strong> con opere di <strong>arazzo in ordine cronologico dagli anni Quaranta ad oggi<\/strong>.<\/p>\n<h3>8. Portalegre Municipal Museum<\/h3>\n<p><strong>Portalegre Museo Civico<\/strong>: \u00e8 un museo inaugurato nel 1918, installato in una casa nobiliare del XVI secolo, situata accanto alla Cattedrale. Al Museo Municipale di Portalegre, possiamo visitare una collezione di arte sacra dai conventi di Portalegre, maioliche portoghesi dal XVII secolo all&#8217;inizio del XX secolo, mobili di D. Jo\u00e3o V, stili di D. artisti portoghesi, la collezione di Santos Ant\u00f3nio, tabacchiere d&#8217;argento e la prima automobile che circol\u00f2 a Portalegre.<\/p>\n<h3>9. Cappella del Calvario<\/h3>\n<p><strong>Capela do Calv\u00e1rio<\/strong>: \u00e8 una cappella di architettura manierista del XVIII secolo, situata a Portalegre.<\/p>\n<h3>10. Portalegre Castle<\/h3>\n<p><strong>Castelo de Portalegre<\/strong>: \u00e8 un castello di architettura gotica del XIII secolo classificato come Patrimonio Nazionale dal 1946. Il castello di Portalegre era una delle fortificazioni pi\u00f9 importanti, parte del sistema difensivo dell&#8217;Alto Alentejo. Con i recenti lavori di ristrutturazione, il castello \u00e8 stato trasformato in rovine di un castello medievale con un mix di architettura contemporanea.<br \/>\nSulle mura del castello intorno a Portalegre troviamo le <strong>Portas do Postigo<\/strong>,<br \/>\n<strong>Portas de Alegrete<\/strong>, <strong>Portas de Elvas<\/strong>, <strong>Portas da Deveza<\/strong>, <strong>Portas do Esp\u00edrito Santo<\/strong>, <strong>Portas do Bispo<\/strong>, <strong>Portas de S\u00e3o Francisco<\/strong>, e le <strong>Portas de \u00c9vora<\/strong>.<\/p>\n<h3>11. <strong>Miradouro da Serra<\/strong><\/h3>\n<p><strong>Miradouro da Serra<\/strong>: \u00e8 un belvedere situato nella Serra de Portalegre, a un&#8217;altitudine di circa 670 metri, che offre una vista panoramica sulla citt\u00e0 di Portalegre.<\/p>\n<h3>12. <strong>Cappella di Nossa Senhora da Penha<\/strong><\/h3>\n<p><strong>Cappella di Nossa Senhora da Penha<\/strong>: \u00e8 una cappella classificata come Edificio di Interesse Pubblico, situata sulla sommit\u00e0 di una collina a Serra da Penha ad un&#8217;altitudine di circa 628 metri, vicino alla Estrada Nacional 18, vicino a Portalegre . All&#8217;esterno della cappella troviamo il <strong>Miradouro da Penha<\/strong>, da dove possiamo godere di una vista panoramica sul paesaggio circostante.<\/p>\n<h3>13. I palazzi e le dimore signorili di Portalegre<\/h3>\n<ul>\n<li>Pal\u00e1cio dos Tavares Falc\u00f5es, XVI secolo<\/li>\n<li>Pal\u00e1cio dos Caldeira Castelo-Branco, XVI-XVII secolo<\/li>\n<li>Palazzo episcopale, XVI-XVII secolo<\/li>\n<li>Municipio, XVII secolo<\/li>\n<li>Palazzo Giallo, XVII secolo<\/li>\n<li>Palazzo Andrade e Sousa, XVII secolo<\/li>\n<li>Palazzo Achioli, XVII secolo<\/li>\n<li>Palazzo Avilez del XVIII secolo<\/li>\n<li>Palazzo Caldeira de Castel-Branco Barahona, o Palazzo<\/li>\n<li>Barahona, XVIII secolo<\/li>\n<li>Palazzo P\u00f3voas, XVIII secolo<\/li>\n<li>Solar dos Viscondes de Portalegre<\/li>\n<li>Solar das Avencas<\/li>\n<\/ul>\n<h3>14. Le fonti di Portalegre<\/h3>\n<ul>\n<li>Fonte do Outeiro, con lo stemma della citt\u00e0<\/li>\n<li>Fontane Corro<\/li>\n<li>Fontana di Tr\u00eas Bicas, sormontata da un balcone<\/li>\n<li>Fonte da Concha<\/li>\n<li>Fonte da Boneca, realizzata in liso<\/li>\n<li>Fonte do Mergulho, fornita dal Convento di Santa Clara<\/li>\n<li>Fontana della Misericordia<\/li>\n<li>Fonte Nova, dello scultore Augusto Desirat<\/li>\n<li>Fontana Rossio<\/li>\n<li>Fontana del Nettuno<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Altri_luoghi_da_visitare_nel_quartiere_di_Portalegre\"><\/span>Altri luoghi da visitare nel quartiere di Portalegre<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3>Castello di Marv\u00e3o<\/h3>\n<p><strong>Castelo de Marv\u00e3o<\/strong>: \u00e8 un castello situato nel <strong>Parco Naturale di S\u00e3o Mamede<\/strong>, con una costruzione del castello iniziata nel XII secolo e completata nel XIII secolo. Era importante come <strong>la prima linea di difesa del paese nella Guerra di Restauro<\/strong> e durante le invasioni francesi del XIX secolo. Le principali attrazioni del castello sono il mastio, un ristorante, un centro interpretativo di Portalegre e una sala espositiva.<\/p>\n<ul>\n<li><strong>Marv\u00e3o<\/strong>: \u00e8 un villaggio portoghese di circa 500 abitanti situato vicino al confine tra Portogallo e Spagna. Marv\u00e3o si trova in cima alla Serra do Sapoio, con le mura del castello che proteggono l&#8217;intero villaggio. Marv\u00e3o \u00e8 una delle 21 meraviglie del Portogallo.<br \/>\nL&#8217;eccezionale patrimonio di Marv\u00e3o comprende il <strong>Castelo de Marv\u00e3o<\/strong>, la Cappella dell&#8217;Esp\u00edrito Santo, la Casa da Cultura, il Convento di Nossa Senhora da Estrela, il Museo Municipale, la <strong>Citt\u00e0 romana di Ammaia<\/strong>, il Lagar \/ Museu Ant\u00f3nio Picado Nunes, Quinta Pedag\u00f3gica das Avel\u00e3s e Torre da Portagem.<br \/>\nIntegrato nel Parco Naturale della Serra de S\u00e3o Mamede, Marv\u00e3o \u00e8 un comune segnato dalla natura, con enfasi sul fiume Sever e la Serra de S\u00e3o Mamede. Marv\u00e3o \u00e8 il capoluogo del comune, con le parrocchie di Beir\u00e3, Santa Maria de Marv\u00e3o, Santo Ant\u00f3nio das Areias e S\u00e3o Salvador da Aramenha.<br \/>\nVicino a Marv\u00e3o troviamo la <strong>Torre medievale di Portagem<\/strong>, una torre quadrangolare, probabilmente del XIV secolo, destinata alla sorveglianza del <strong>Ponte romano di Portagem<\/strong>, un ponte costruito sul <strong>fiume Sever<\/strong> alla fine del XVI secolo, all&#8217;inizio del XVII secolo con pietre di granito riutilizzate da un primitivo ponte romano. Qui troviamo la <strong>Praia Fluvial de Portagem<\/strong>, una spiaggia fluviale con l&#8217;acqua del fiume Saver.<\/li>\n<li><strong>Ammaia<\/strong>: sono le rovine di un&#8217;antica citt\u00e0 romana della fine del I secolo a.C., situata nel Parco Naturale della Serra de S\u00e3o Mamede, classificata come Monumento Nazionale dal 1949.<\/li>\n<\/ul>\n<h3>Castello di Elvas<\/h3>\n<p><strong>Castelo de Elvas<\/strong>: \u00e8 un castello del XIII secolo classificato come Patrimonio dell&#8217;Umanit\u00e0, Monumento Nazionale, situato in posizione dominante sul villaggio di Elvas e sul fiume Guadiana. Il castello di Elvas fa parte del progetto <strong>Turismo Militare<\/strong>, che presenta itinerari storici con l&#8217;obiettivo di far conoscere la <strong>Storia Militare del Portogallo<\/strong>.<\/p>\n<ul>\n<li><strong>Elvas<\/strong>: \u00e8 una citt\u00e0 portoghese di circa 20mila abitanti situata vicino al confine con la Spagna. Elvas fu popolata da Visigoti, Celti, Romani e Arabi fino alla Riconquista nel 1229. Il <strong>centro storico della citt\u00e0 di Elvas<\/strong> \u00e8 protetto dal <strong>pi\u00f9 grande insieme di fortificazioni bastionate del mondo<\/strong>, con un perimetro di da otto a dieci chilometri, in un&#8217;area di circa 300 ettari.<br \/>\nParte della citt\u00e0 di <strong>Elvas<\/strong> \u00e8 stata classificata come <strong>Patrimonio dell&#8217;Umanit\u00e0<\/strong>, vale a dire il <strong>centro storico<\/strong>, le <strong>mura bastionate del XVII secolo<\/strong>, il <strong>Forte de Santa Luzia<\/strong>, il <strong>Forte da Gra\u00e7a<\/strong>, l &#8216;<strong>Aqueduto da Amoreira<\/strong> con gli 843 archi che lo compongono, il <strong>forte S\u00e3o Pedro<\/strong>, il <strong>forte S\u00e3o Mamede<\/strong> e <strong>Fortim de S\u00e3o Domingos<\/strong><strong>. <\/strong>Il patrimonio di Elvas comprende anche il Museo Municipale di Fotografia Jo\u00e3o Carpinteiro, il Museo Militare del Forte di Santa Luzia, il Museo di Arte Contemporanea, il Museo Rurale e il Museo Archeologico.<br \/>\nElvas ha una grande importanza nel <strong>turismo equestre<\/strong>, in particolare attraverso il Centro ippico di S\u00e3o Br\u00e1s e il Parque e Clube de Tiro e Ca\u00e7a de Elvas.<br \/>\nLa gastronomia di Elvas, una cucina tipica dell&#8217;Alentejo, comprende specialit\u00e0 come zuppe di pane, agnello arrosto, merluzzo dorato, migas di coriandolo, olive Elvas e prugne Elvas.<\/li>\n<li><strong>Aqueduto da Amoreira<\/strong>: \u00e8 un magnifico acquedotto del XVI e XVII secolo, classificato come patrimonio mondiale dell&#8217;UNESCO, parte della &#8220;Citt\u00e0 di confine e guarnigione di Elvas e le sue fortificazioni, monumento nazionale, considerato il pi\u00f9 grande acquedotto nella penisola iberica., con 8,5 chilometri di lunghezza, 843 archi con pi\u00f9 di cinque archi e torri che si elevano a 31 metri di altezza.<\/li>\n<li><strong>Forte di Nossa Senhora da Gra\u00e7a<\/strong>: o <strong>Fort Conde de Lippe<\/strong>, \u00e8 una spettacolare fortificazione del XVIII secolo, con una cittadella, classificata come <strong>Patrimonio dell&#8217;Umanit\u00e0 dall&#8217;UNESCO, <\/strong>Monumento Nazionale, situata sul top do Monte da Gra\u00e7a, parte della &#8220;Citt\u00e0 Fronteiri\u00e7a e Guarni\u00e7\u00e3o de Elvas e le sue fortificazioni. Il Forte di Nossa Senhora da Gra\u00e7a \u00e8 uno spazio ampio e ben conservato che richiede tempo per essere esplorato. Il Forte \u00e8 costituito da tre linee difensive considerate <strong>un&#8217;opera d&#8217;arte di architettura militare<\/strong> Il Forte di Nossa Senhora da Gra\u00e7a era la fortezza che ha permesso di completare il circuito difensivo della citt\u00e0 di Elvas.<\/li>\n<li><strong>Forte di Santa Luzia<\/strong>: \u00e8 un forte del 1648 classificato <strong>Patrimonio dell&#8217;Umanit\u00e0 dall&#8217;UNESCO<\/strong>, Monumento Nazionale, progettato con pianta a stella, destinato a difendere il fronte meridionale della citt\u00e0 di Elvas.<\/li>\n<li><strong>Museo militare di Elvas<\/strong>:<\/li>\n<\/ul>\n<h3>Monumento naturale di Portas de R\u00f3d\u00e3o<\/h3>\n<p><strong>Monumento naturale di Portas de R\u00f3d\u00e3o<\/strong>: noto come Portas de Rod\u00e3o, \u00e8 un luogo tranquillo creato da una formazione rocciosa tra scarpate alte 170 metri che simulano due porte con il fiume Tago al centro, creando un paesaggio naturale di grande attrazione . Dopo le Portas de Rod\u00e3o c&#8217;\u00e8 un grande lago, che testimonia che la Portao de Rod\u00e3o \u00e8 stata originata dall&#8217;erosione di milioni di anni. In cima a Portas de Rod\u00e3o possiamo visitare il castello di Rei Wamba, il villaggio paleolitico di Vilas Ruivas. Questo \u00e8 un luogo eccellente per il birdwatching, con avvistamenti regolari di avvoltoi, rapaci e altre specie. Le Portas de Rod\u00e3o sono uno dei geositi del <strong>Geopark Naturtejo da Meseta Meridional<\/strong> che fa parte del World Geoparks Network, creato dall&#8217;UNESCO e copre un&#8217;area che comprende i comuni di Castelo Branco, Idanha-a-Nova, Nisa, Oleiros, Proen\u00e7a -a-Nova e Vila Velha de R\u00f3d\u00e3o.<\/p>\n<h3>Castelo de Vide<\/h3>\n<ul>\n<li><strong>Castelo de Vide<\/strong>: \u00e8 un villaggio portoghese situato su una collina nella Serra de S\u00e3o Mamede con circa 3400 abitanti. Castelo de Vide \u00e8 considerato da molti come &#8220;Sintra do Alentejo&#8221;, un villaggio dell&#8217;Alentejo dalle peculiarit\u00e0 uniche, con case imbiancate a calce, strade in pendenza, circondate da mura. A Castelo de Vide possiamo visitare un importante e vasto patrimonio, vale a dire: il <strong>castello medievale di Vide<\/strong>, il <strong>ebreo di Castelo de Vide<\/strong>, un quartiere ebraico che comprende una <strong>sinagoga<\/strong>, Pra\u00e7a D Pedro V, la Chiesa di S\u00e3o Jo\u00e3o Batista, la Chiesa Madre e le case signorili, che troviamo in tutto il villaggio. Vicino al villaggio di Castelo de Vide troviamo il Monte da Pena, un luogo dove si trova la <strong>Cappella di Nossa Senhora da Pena<\/strong>, con un punto di vista sul Castelo de Vide. La moderna area di Castelo de Vide dispone di piscine comunali, piscine con scivoli, un padiglione comunale, una pista di atletica e un campo da calcio. Le feste pi\u00f9 importanti a Castelo de Vide sono il <strong>Carnaval Trapalh\u00e3o<\/strong>, che si svolge ogni anno a febbraio, la <strong>Semana Santa<\/strong>, che si svolge ogni anno ad aprile, e il <strong>Mercato medievale<\/strong>, che si tiene luogo che si tiene ogni anno in agosto e settembre. Il <strong>Festival Andan\u00e7as<\/strong> &#8211; Festival Internazionale di Musica e Danze Tradizionali, che si tiene ogni anno ad agosto, sta acquistando importanza negli ultimi anni.<\/li>\n<li><strong>Castelo Medieval de Vide<\/strong>: \u00e8 un castello del XIV secolo, classificato come monumento nazionale, situato sulla sommit\u00e0 della collina della catena montuosa di S\u00e3o Mamede. Il Castello Medievale di Vide \u00e8 una delle maggiori attrazioni del quartiere Portalegre. All&#8217;interno delle mura troviamo il borgo medievale, il quartiere ebraico e la sinagoga.<\/li>\n<li><strong>Anta da Melri\u00e7a<\/strong>: situato vicino al villaggio di Castelo de Vide, \u00e8 costituito da un monumento megalitico di roccia eretta, che era una funzione funeraria.<\/li>\n<\/ul>\n<h3>Castello di Belver a Gavi\u00e3o<\/h3>\n<p><strong>Castelo de Belver<\/strong> \u00e8 un castello del XIII secolo, considerato uno dei castelli pi\u00f9 completi dell&#8217;architettura militare medievale portoghese, situato in posizione dominante sulla confluenza del torrente Belver con la riva destra del fiume Tago.<br \/>\n<strong>Gavi\u00e3o<\/strong>: \u00e8 un villaggio di circa 3200 abitanti, profondamente segnato dalla bellezza naturale circostante. Nel comune di Gavi\u00e3o, vale la pena visitare il <strong>Castelo de Belver<\/strong>, il <strong>ponte sul fiume Tagus de Belver<\/strong>, il <strong>belvedere di Outeirinho<\/strong>, il <strong>belvedere di Pintalgaio<\/strong>, il <strong>cappella Nossa Senhora do Pilar<\/strong>, il centro di interpretazione del castello di Belver, il sentiero Fonte Velha, la chiesa madre Gavi\u00e3o, il museo Sab\u00e3o, il museo della vite e del vino, il museo delle mante e degli arazzi Belver, spiaggia del fiume Alamal, osservatorio di Avifauna e Ribeira da Venda.<\/p>\n<ul>\n<li><strong>Praia Fluvial de Ortiga<\/strong>: \u00e8 una spiaggia di sabbia fluviale sul fiume Tago a ridosso della diga di Belver, dove si trova il campeggio Ortiga. Nelle vicinanze si possono intraprendere alcuni sentieri a contatto con la natura, dove troviamo il <strong>belvedere naturale di Cova<\/strong>, la <strong>Terrazza GEOSSITIO con materiale paleolitico<\/strong> e il borgo di Ortiga.<\/li>\n<li><strong>Anta do Penedo Gordo<\/strong>: un monumento megalitico situato a nord della diga di Belver.<\/li>\n<\/ul>\n<h3>Castello di Alegrete<\/h3>\n<p><strong>Castelo de Alegrete<\/strong>: \u00e8 un piccolo castello di architettura gotica costruito nel Medioevo, situato nel villaggio di Alegrete, Portalegre. Dal castello abbiamo una vista panoramica del paese e del paesaggio montano circostante. Per la sua posizione era una delle fortificazioni pi\u00f9 importanti dell&#8217;Alto Alentejo.<\/p>\n<h3>Fluvi\u00e1rio de Mora<\/h3>\n<p><strong>Fluvi\u00e1rio de Mora<\/strong>: \u00e8 un fiume situato nel Parco Ecologico di Gameiro, nella parrocchia di Cabec\u00e7\u00e3o. Il Fluvi\u00e1rio de Mora \u00e8 composto da un insieme di acquari dedicati agli ecosistemi d&#8217;acqua dolce, con l&#8217;esposizione di habitat rappresentativi del corso di un fiume iberico, dalla sorgente, attraverso la foce, al mare. Fluvi\u00e1rio de Mora ha programmi scientifici e pedagogici presentati su diversi temi, vale a dire, Lontr\u00e1rio, la sala Saramugo, la sala Monstros do Rio, la sala delle esposizioni multimediali, l&#8217;aula, un auditorium e la sala degli habitat esotici, con il Rio delle Amazzoni e l&#8217;African Great Specie dei laghi. \u00c8 un&#8217;attrazione speciale per famiglie e bambini, un luogo speciale per conoscere la natura. Vicino al Fluvi\u00e1rio de Mora possiamo visitare il villaggio di Mora, dove troviamo:<\/p>\n<ul>\n<li><strong>Museo Interattivo del Megalitismo<\/strong>: \u00e8 un museo situato nella vecchia stazione ferroviaria di Mora, premiato con il premio &#8220;Miglior progetto pubblico&#8221;, dove possiamo conoscere il patrimonio megalitico del Comune di Mora attraverso tre spazi rappresentativi di la quotidianit\u00e0 delle popolazioni, dedicata al tema: &#8220;Vita, morte e contemplazione&#8221; attraverso un video 3D che racconta la vita in un villaggio neolitico.<\/li>\n<\/ul>\n<h3>Parco ecologico di Gameiro<\/h3>\n<p><strong>Parque Ecol\u00f3gico do Gameiro<\/strong>: \u00e8 un parco naturale che coinvolge il <strong>Fluvi\u00e1rio de Mora<\/strong> a Vila de Cabec\u00e7\u00e3o, dove troviamo una spiaggia fluviale, campeggio, area picnic, parco giochi per bambini, bar \/ caffetteria, <strong>Passerelle in legno Gameiro<\/strong> lungo la Ribeira da Raia, parco giochi e Centro di interpretazione ambientale. Il Parco Ecologico Gameiro \u00e8 il luogo ideale per godersi una giornata nella natura, con un campo da calcio, una caffetteria, docce, molta ombra, in un ambiente pulito e attento.<\/p>\n<h3>Castello di Alter do Ch\u00e3o<\/h3>\n<p><strong>Castello Alter do Ch\u00e3o<\/strong>: \u00e8 un castello di architettura medievale, costruito nel XIV secolo, con mura in scisto e granito, rinforzato da sei torri. Il castello di Alter do Ch\u00e3o \u00e8 un&#8217;antica difesa della regione dell&#8217;Alentejo, situata nel villaggio portoghese di Alter do Ch\u00e3o, un villaggio situato nel distretto di Portalegre con circa 3100 abitanti. Alter do Ch\u00e3o fu fondata nel 204 d.C. con il nome di Elteri sotto l&#8217;occupazione romana. Qui possiamo visitare il Castello Alter do Ch\u00e3o, la <strong>Chiesa di Nosso Senhor Jesus do Outeiro<\/strong>, la Chiesa della Miseric\u00f3rdia, la Cappella di Santana e la <strong>Stud Farm<\/strong> fondata nel 1748 dal re portoghese D Jo\u00e3o V , con l&#8217;obiettivo di creare cavalli lusitano per il maneggio reale.<\/p>\n<h3>Museo Militare di Elvas<\/h3>\n<p><strong>Museo Militare di Elvas<\/strong>: \u00e8 un museo situato all&#8217;interno delle mura della citt\u00e0 di Elvas, nell&#8217;edificio del <strong>Convento de S\u00e3o Domingos<\/strong> e della <strong>Igreja de S\u00e3o Domingos<\/strong>. Nel museo militare di Elvas possiamo vedere gli <strong>elementi di trazione animale e imbracatura militare<\/strong>, il servizio sanitario nelle diverse <strong>specialit\u00e0 mediche militari<\/strong>, la <strong>Collezione di veicoli militari<\/strong>, ovvero un militare carro armato presente all&#8217;ingresso del museo, il carro armato M42-AI Stuart, modello dal 1942, i veicoli M47 Patton e Unimog 411, utilizzati nelle campagne coloniali portoghesi, le <strong>comunicazioni militari<\/strong>, il <strong>Centro di Interpretazione del Patrimonio Elvas<\/strong> e il <strong>Centro di Animazione e Formazione Equestre di Elvas<\/strong><\/p>\n<h3>Castello di Campo Maior<\/h3>\n<p><strong>Castello di Campo Maior<\/strong>: \u00e8 un castello di architettura militare costruito da D. Dinis nel 1310, classificato Monumento Nazionale, situato nel villaggio Alentejo di <strong>Campo Maior<\/strong>. Campo Maior divenne il centro militare pi\u00f9 importante del Portogallo, dopo Elvas. Aveva la funzione di difesa di confine, motivo per cui fu ampliata nel XV secolo con una cinta muraria che ospitava l&#8217;intero perimetro urbano. All&#8217;interno delle mura del paese possiamo visitare altre attrazioni, ovvero il <strong>Lagar Museu do Pal\u00e1cio Visconde d &#8216;Oliv\u00e3<\/strong>, la <strong>Cappella delle Ossa di Campo Maior<\/strong>, la <strong>Igreja Matriz<\/strong>, <strong>Igreja de S\u00e3o Jo\u00e3o Batista<\/strong>, il <strong>Museo all&#8217;aperto di Campo Maior<\/strong> a <strong>Pra\u00e7a da Rep\u00fablica<\/strong> dove troviamo la Gogna di Campo Maior e il municipio, e ai margini del centro storico con l&#8217;ampliamento di nella nuova citt\u00e0 di Campo Larger troviamo il <strong>Giardino Comunale<\/strong>, con aree verdi, terrazze, e la <strong>statua del Comendador Nabeiro<\/strong>, un uomo d&#8217;affari della regione che ha contribuito allo sviluppo locale attraverso la creazione di posti di lavoro con il caff\u00e8 industria. Da segnalare il <strong>patrimonio naturalistico di Campo Maior<\/strong>, ovvero la <strong>diga del fiume Caia<\/strong> e la <strong>diga di Abrilongo<\/strong>. Campo Maior \u00e8 noto per le feste popolari, che si tengono ogni anno a settembre. Durante queste feste, il villaggio viene \u201cvestito\u201d di fiori di carta e trasformato in un immenso giardino<\/p>\n<ul>\n<li><strong>Science and Caf\u00e9 Center<\/strong>: \u00e8 uno spazio creato dall&#8217;industriale Comendador Rui Nabeiro, in un edificio con una superficie totale di 3426 m2, dove possiamo visitare e conoscere la storia, il processo di trasformazione e tutto ci\u00f2 che riguarda come il mondo del caff\u00e8, attraverso mostre e interattivit\u00e0. Il Science and Coffee Center appartiene al gruppo Nabeiro, creatore del marchio portoghese Delta Caf\u00e9 dal 1961. Un luogo da visitare &#8230;<\/li>\n<\/ul>\n<h3>Adega Mayor<\/h3>\n<p><strong>Adega Mayor<\/strong>: \u00e8 una cantina progettata dall&#8217;architetto Siza Vieira, dove in un campo di 350 ettari \u00e8 stata creata una cantina, con vista sul vigneto, un uliveto, la Spagna e la Serra de Portalegre. Qui possiamo sperimentare laboratori, visite guidate nel mondo degli aromi del vino prodotti in questa tenuta, degustazioni di prodotti gastronomici della regione e un tour della tenuta Adega Mayor.<\/p>\n<h3>Castello di Amieira do Tejo<\/h3>\n<p><strong>Castello di Amieira do Tejo<\/strong>: \u00e8 un castello di architettura gotica del XIV secolo, che integrava la linea di difesa del confine tra Portogallo e Spagna, situato nel villaggio di Amieira do Tejo. Il Castello di Amieira \u00e8 un piccolo castello in buone condizioni.<\/p>\n<h3>Museo del sapone<\/h3>\n<p><strong>Museu do Sab\u00e3o<\/strong>: \u00e8 un museo installato nella vecchia scuola elementare di Belver, che preserva la cultura dell&#8217;industria del sapone dal XVI secolo, avvenuta principalmente nelle zone dell&#8217;Alto Alentejo e del Castelo Branco. L&#8217;importanza economica e sociale nel villaggio di Belver derivata dall&#8217;industria del sapone era notevole per la presenza di diversi produttori artigianali e per la Royal Soap Factory. Il Museo del sapone \u00e8 un museo con molte informazioni sulla produzione, la storia e l&#8217;uso del sapone, che mira a diffondere le conoscenze acquisite dagli antenati e ad onorare la memoria dei produttori di sapone di Belver.<\/p>\n<h3>Centro di interpretazione della battaglia di Atoleiros<\/h3>\n<p><strong>Centro di Interpretazione della Battaglia di Atoleiros<\/strong>: \u00e8 un museo che rappresenta una ricostruzione, attraverso mezzi multimediali, della Battaglia di Atoleiros condotta il 6 aprile 1384 nei pressi del villaggio di Fronteira.<\/p>\n<h3>Rail Bike Marv\u00e3o<\/h3>\n<p><strong>Rail Bike Marv\u00e3o<\/strong>: \u00e8 un&#8217;esperienza con due percorsi in una macchina a pedali, che scorre sulla vecchia linea ferroviaria Marv\u00e3o, tra le stazioni storiche del Parco Naturale della Serra de S\u00e3o Mamede, permettendoti di osservare la natura e la vita selvaggia, un ponte alto 30 metri e viste panoramiche sul Castello di Marv\u00e3o e sul villaggio storico di Castelo de Vide. Questa esperienza richiede uno sforzo fisico.<\/p>\n<h3>Menhir de Meada<\/h3>\n<p><strong>Menhir de Meada<\/strong>: \u00e8 un menhir del periodo neocalcolitico 2500-3500 a.C., situato a Castelo de Vide, classificato come il pi\u00f9 grande Menhir della penisola iberica, con circa 4 metri di altezza, classificato Monumento Nazionale . L&#8217;area dei menhir \u00e8 circondata da menhir pi\u00f9 piccoli e querce da sughero.<\/p>\n<h3>Tapiro di Pavia<\/h3>\n<p><strong>Tapiro di Pavia<\/strong>: \u00e8 un tapiro risalente al IV o III millennio a.C. e trasformato nella <strong>cappella di S\u00e3o Dinis<\/strong> nel XVII secolo, situata al centro del piccolo villaggio di Paiva.<\/p>\n<h3>Ponte di Nossa Senhora da Ajuda<\/h3>\n<p><strong>Ponte Nossa Senhora da Ajuda<\/strong>: \u00e8 un ponte cinquecentesco lungo trecentottanta metri e largo cinque metri e mezzo, sorretto da diciannove archi, creando un fantastico paesaggio sul fiume Guadiana.<\/p>\n<h3>Monastero di Flor da Rosa<\/h3>\n<p><strong>Monastero Flor da Rosa<\/strong>: o Monastero dell&#8217;Ordine dell&#8217;Ospedale da Flor da Rosa, \u00e8 un monastero fortificato del XIV secolo classificato Monumento Nazionale, trasformato nel 1995 in <strong>unit\u00e0 alberghiera di Pousadas de Portugal . <\/strong>Nella chiesa del convento si trovano attualmente il <strong>Centro di scultura medievale del Museo Nazionale di Arte Antica<\/strong> e una mostra di sculture di Jo\u00e3o Cutileiro.<\/p>\n<ul>\n<li><strong>Anta da Aldeia da Mata<\/strong>: \u00e8 un monumento megalitico ben conservato, situato vicino al Monastero Flor da Rosa, situato in una tenuta privata circondata da pascoli e querce da sughero, un tipico paesaggio dell&#8217;Alentejo. Per visitare il Tapiro di Aldeia da Mata dobbiamo attraversare il cancello della propriet\u00e0. All&#8217;interno della propriet\u00e0 privata sono presenti bovini e si consiglia cautela con gli animali.<\/li>\n<\/ul>\n<h3>Castello di Avis<\/h3>\n<p><strong>Castelo de Avis<\/strong>: \u00e8 un castello \u00e8 un castello del XIII secolo situato nel villaggio di <strong>Avis<\/strong>, un villaggio portoghese situato ad un&#8217;altitudine di 201 metri con circa 4200 abitanti. Il villaggio di Avis era la sede dell&#8217;Ordine di Avis, uno dei pi\u00f9 importanti ordini militari del Portogallo. Il villaggio respira storia, in particolare il centro storico, il <strong>Castelo de Avis<\/strong>, l&#8217;Igreja Matriz, l&#8217;Igreja de Ervedal, il Museu do Campo Alentejano, il Centro Interpretativo da Ordem de Avis e il convento di S\u00e3o Bento da Order of Avis. Avis dispone di luoghi per la pratica degli sport all&#8217;aria aperta e del turismo rurale, ovvero il campeggio del bacino idrico del Maranh\u00e3o e il complesso del club nautico Avis, con spiaggia fluviale, piscine, ristorante e aree verdi. Le feste e i pellegrinaggi pi\u00f9 importanti in Avis sono la Fiera iberica medievale che si svolge a maggio e la Feira Franca de Avis, che si svolge a luglio.<\/p>\n<h3>Museo municipale della fotografia Jo\u00e3o Carpinteiro<\/h3>\n<p><strong>Museo Municipale di Fotografia Jo\u00e3o Carpinteiro<\/strong>: \u00e8 un museo installato nell&#8217;edificio del vecchio Cinema Central, dove possiamo conoscere la storia della fotografia, una collezione di macchine fotografiche del Dr. Jo\u00e3o Carpinteiro, come un laboratorio fotografico opere di sviluppo, una libreria e una banca di immagini.<\/p>\n<h3>Diga di P\u00f3voa<\/h3>\n<p><strong>Diga di P\u00f3voa<\/strong>: \u00e8 una diga vicino a Castelo de Vide, che forma il piccolo bacino idrico della diga di P\u00f3voa e Meadas. \u00c8 un luogo immerso nella natura, ricercato per gli sport all&#8217;aria aperta e per i picnic.<\/p>\n<h3>Ponte Vila Formosa<\/h3>\n<p><strong>Ponte de Vila Formosa<\/strong>: \u00e8 un antico <strong>ponte romano<\/strong> del I o II secolo, con 6 arcate divise in 100 metri di lunghezza sul torrente Seda, situato al km 8 della EN. 369. Il ponte fa parte dell&#8217;antica strada romana che collegava Lisbona a M\u00e9rida in Spagna. Per le sue buone condizioni viene ancora utilizzata per la circolazione automobilistica. Il ponte Vila Formosa \u00e8 classificato come monumento nazionale.<\/p>\n<h3>Caia Dam<\/h3>\n<p><strong>Barragem do Caia<\/strong>: \u00e8 la diga con l&#8217;invaso pi\u00f9 grande del comprensorio di Portalegre, alimentata dal fiume Caia. La diga \u00e8 ricercata per gli sport acquatici, ovvero windsurf, kitesurf, canoa, stand up paddle, mountain bike e sport nella natura, ovvero birdwatching, escursionismo e pesca.<\/p>\n<h3>Convento di Nossa Senhora da Estrela<\/h3>\n<p><strong>Convento di Nossa Senhora da Estrela<\/strong>: si tratta di un convento del XV secolo situato nel villaggio di Santa Maria de Marv\u00e3o, classificato come Bene di Interesse Pubblico.<\/p>\n<h3>Vila de Arronches<\/h3>\n<ul>\n<li><strong>Arronches<\/strong>: \u00e8 un villaggio portoghese situato vicino al confine con circa 2800 abitanti. Arronches si trova nel Parco Naturale della Serra de S\u00e3o Mamede, che permette di praticare attivit\u00e0 sportive all&#8217;aperto e passeggiate in mezzo alla natura. Nel villaggio di Arronches segnaliamo il Castello di Arronches, la Chiesa Madre, la Chiesa della Miseric\u00f3rdia, la Chiesa di Nossa Senhora da Luz, la torre medievale e il Passeio do Vassalo.<\/li>\n<\/ul>\n<h3>Vila de Fronteira<\/h3>\n<ul>\n<li><strong>Fronteira<\/strong>: \u00e8 un tradizionale villaggio portoghese con circa 3000 abitanti, fondato dal re portoghese D Dinis nel XIII secolo. Vicino a Fronteira troviamo <strong>Atoleiros<\/strong>, il luogo in cui D Nuno \u00c1lvares Pereira sconfisse i castigliani nel 1384, garantendo l&#8217;indipendenza del Portogallo. Nel villaggio di Fronteira, la Igreja Matriz, la Igreja dos Senhor dos M\u00e1rtires, l&#8217;edificio Pa\u00e7os do Concelho, la stazione ferroviaria con <strong>pannelli di piastrelle raffiguranti lo stile di vita della regione<\/strong>, i palazzi signorili del XVIII secolo, l&#8217;Interpretazione Centro della battaglia di Atoleiros, le Termas da Sulf\u00farea, il belvedere del Santuario di Nossa Senhora de Vila Velha e la spiaggia fluviale di Ribeira Grande.<br \/>\nLe feste e i pellegrinaggi pi\u00f9 importanti a Fronteira sono: le Feste d&#8217;Onore di Nossa Senhora da Vila Velha che si svolgono ogni anno in agosto, la Commemorazione della Battaglia di Atoleiros, festa municipale che si svolge ogni anno ad aprile, la Fiera medievale, che si tiene si svolge ogni anno ad aprile e il festival in onore di Nossa Senhora das Candeias, che si svolge ogni anno a febbraio.<\/li>\n<\/ul>\n<h3>Vila de Monforte<\/h3>\n<ul>\n<li><strong>Monforte<\/strong>: \u00e8 un paese di 3000 abitanti situato nel comune di Portalegre. Monforte \u00e8 noto per essere il luogo di origine <strong>del cane Serra d&#8217;Aires e del rafeiro dell&#8217;Alentejo<\/strong>. A Monforte si evidenziano il Centro di riproduzione Rafeiro Alentejano, il Centro interpretativo Tauromatic, Herdade do Perdig\u00e3o, la chiesa di Calv\u00e1rio, la chiesa di Nossa Senhora da Concei\u00e7\u00e3o, la chiesa di S\u00e3o Jo\u00e3o Batista, il museo municipale, il vecchio ponte di Monforte, le rovine di Palma, la Torre das Figueiras e la Torre do Frade.<\/li>\n<\/ul>\n<h3>Ponte de Sor<\/h3>\n<ul>\n<li><strong>Ponte de Sor<\/strong>: \u00e8 una citt\u00e0 e un comune nel distretto di Portalegre con circa 15000 abitanti. Nel comune di Ponte de Sor possiamo visitare il Centro di Arte e Cultura, la Chiesa Madre di Ponte de Sor, l&#8217;Albufeira de Montargil, le sei cappelle della Galveia, il parco acquatico O\u00e1sis Parque, i mulini ad acqua rotanti, il Nucleo megalitico de Montargil, la necropoli di Santo Andr\u00e9 e l&#8217;area fluviale di Ponte de Sor.<br \/>\nLe feste e i pellegrinaggi pi\u00f9 importanti a Ponte de Sor sono il festival <strong>Salgueirinha<\/strong> che si svolge ogni anno il luned\u00ec di Pasqua, il festival <strong>Centrum Sete Sois Sete Luas<\/strong>, che si svolge ogni anno tra luglio e settembre, il <strong>La fiera di ottobre<\/strong>, che si svolge ogni anno in ottobre, e il <strong>Festival internazionale delle mongolfiere<\/strong> che si svolge ogni anno a novembre. Ponte de Sor \u00e8 servito dall &#8216;<strong>Aerodromo Municipale di Ponte de Sor<\/strong>, con voli in aliante, e corsi superiori relativi ad aeronautica \/ aerospaziale, tenuti presso l&#8217;edificio Campus Universit\u00e1rio.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"La_gastronomia_di_Portalegre\"><\/span>La gastronomia di Portalegre<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>I piatti tipici di Portalegre sono:<\/p>\n<ul>\n<li>Spezzatino di cereali<\/li>\n<li>Quaglia fritta<\/li>\n<li>Crato Stew<\/li>\n<li>Stufato di agnello<\/li>\n<li>Lacon arrosto<\/li>\n<li>Lepre con fagioli bianchi<\/li>\n<li>Lepre con riso<\/li>\n<li>Marheiros \u00e0 Belverense<\/li>\n<li>Pernice marinata<\/li>\n<li>Pastelli di Santa Clara<\/li>\n<li>Portalegre Queijadas<\/li>\n<li>Sericaia<\/li>\n<li>Formaggio Nisa<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Il_mestiere_di_Portalegre\"><\/span>Il mestiere di Portalegre<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>L&#8217;ex libris dell&#8217;artigianato della citt\u00e0 \u00e8 l&#8217;arte dell&#8217;arazzo, considerato il miglior arazzo del Portogallo e uno dei migliori al mondo. L&#8217;artigianato di Portalegre include anche le tradizioni del fabbro e della latta.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Storia_di_Portalegre\"><\/span>Storia di Portalegre<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Portalegre \u00e8 stata fondata nel periodo dell&#8217;occupazione romana, essendo chiamata Portus Alacer o Porto Alegre. Portalegre fungeva da rifugio per i viaggiatori di passaggio nella regione. Portalegre fu fortificato a causa della vicinanza del confine con la Spagna, e nel 1290 fu costruito un castello con dodici torri e sette porte che proteggevano il villaggio dall&#8217;accesso di estranei. Portalegre fu elevata alla categoria di citt\u00e0 nel 1550. Nel XVII secolo fu inaugurata la <strong>Real F\u00e1brica de Lanificios<\/strong>, che contribu\u00ec allo sviluppo della citt\u00e0. Nell&#8217;Ottocento venne costruita la <strong>Robinson Factory<\/strong>, dedicata alla preparazione e trasformazione del sughero. Il 18 luglio 1835 Portalegre fu designata capitale del distretto.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Leconomia_di_Portalegre\"><\/span>L&#8217;economia di Portalegre<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>L&#8217;agricoltura rappresenta la massima importanza nell&#8217;economia del distretto di Portalegre, con la produzione di cereali, olio d&#8217;oliva, noci e vino; bestiame, con la creazione di bovini, caprini, suini e cavalli; l&#8217;industria della panificazione, l&#8217;industria del latte, del caff\u00e8 e del t\u00e8, la produzione di sughero e il turismo. Il distretto di Portalegre ha il punto di residenza cittadina pi\u00f9 grande d&#8217;Europa.<br \/>\nIl turismo \u00e8 cresciuto nell&#8217;interno dell&#8217;Alentejo negli ultimi decenni, con l&#8217;emergere del turismo rurale migliorato con alloggi rurali di qualit\u00e0, turismo naturalistico, enoturismo, turismo nautico associato alle dighe, turismo legato al circuito culturale e religioso, gastronomico ed enoturistico, turismo della salute legato alle terme.<\/p>\n<p>L&#8217;economia imprenditoriale e industriale del distretto di Portalegre \u00e8 sostenuta e sostenuta dall&#8217;esistenza di tredici Zone Industriali:<\/p>\n<ol>\n<li>Zona industriale Alter do Ch\u00e3o<\/li>\n<li>Zona industriale Avis<\/li>\n<li>Zona Industriale Campo Maior<\/li>\n<li>Zona industriale di Castelo de Vide<\/li>\n<li>Zona industriale di Crato<\/li>\n<li>Zona industriale di Elvas<\/li>\n<li>Zona industriale di frontiera<\/li>\n<li>Zona industriale di Gavi\u00e3o<\/li>\n<li>Zona industriale di Marv\u00e3o<\/li>\n<li>Zona Industriale Monforte<\/li>\n<li>Zona industriale di Nisa<\/li>\n<li>Zona industriale di Portalegre<\/li>\n<li>Zona industriale Sousel<\/li>\n<\/ol>\n<h2><span class=\"ez-toc-section\" id=\"Posizione_geografica_del_distretto_di_Portalegre\"><\/span>Posizione geografica del distretto di Portalegre<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Portalegre confina a nord con il distretto di Castelo Branco, a sud con il distretto di \u00c9vora, a ovest con il distretto di Santar\u00e9m e a est con la Spagna. Il <strong>distretto di Portalegre<\/strong> conta <strong>69 parrocchie<\/strong>, divise per <strong>15 comuni<\/strong> comprendenti la citt\u00e0 di Elvas, la citt\u00e0 di Portalegre, la citt\u00e0 di Ponte de Sor, la frazione di Campo Maior, il villaggio de Nisa, il villaggio di Alter do Ch\u00e3o, il villaggio di Castelo de Vide, il villaggio di Fronteira, il villaggio di Arronches, il villaggio di Sousel, il villaggio di Avis, il villaggio di Crato, il villaggio di Gavi\u00e3o, il villaggio di Monforte e il villaggio di Marv\u00e3o.<br \/>\nI fiumi pi\u00f9 importanti nel distretto di Portalegre sono il fiume Avis, il fiume Caia, il fiume Guadiana, il fiume Sever e il fiume Tago. Le montagne pi\u00f9 importanti del distretto di Portalegre sono la catena montuosa del Monte da Penha, la catena montuosa di S\u00e3o Mamede, la catena montuosa del Nisa, la catena montuosa del Marv\u00e3o e la catena montuosa di Portalegre.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Portalegre_Feste_e_Pellegrinaggi\"><\/span>Portalegre Feste e Pellegrinaggi<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li><strong>Made in Portalegre<\/strong>: si tiene nel mese di ottobre, ogni due anni;<\/li>\n<li><strong>Portalegre JazzFest<\/strong>: si tiene ogni anno a febbraio;<\/li>\n<li><strong>Fiera Conventuale della Pasticceria<\/strong>: si tiene ogni anno nel mese di aprile;<\/li>\n<li><strong>Campionato fuoristrada Low 500<\/strong>: si tiene ogni anno in ottobre;<\/li>\n<li><strong>Festival Internazionale del Teatro<\/strong>: si tiene ogni anno a novembre.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Portalegre_Fast_Facts\"><\/span>Portalegre Fast Facts<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li><strong>Popolazione cittadina<\/strong>: circa 22mila abitanti<\/li>\n<li><strong>Fondazione della contea<\/strong>: 1259<\/li>\n<li><strong>Regione<\/strong>: Alentejo<\/li>\n<li><strong>Sotto-regione<\/strong>: Alto-Alentejo<\/li>\n<li><strong>Distretto<\/strong>: Portalegre<\/li>\n<li><strong>Festa comunale<\/strong>: 23 maggio<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Portalegre Portalegre \u00e8 la capitale del distretto con la minor popolazione in Portogallo, situato nel cuore del Parco Naturale della Serra de S\u00e3o Mamede, nella regione dell&#8217;Alentejo e nella sottoregione dell&#8217;Alentejo. \u00c8 una citt\u00e0 ricca di patrimonio culturale, ovvero con artigianato, costumi, gastronomia, folklore, canti e danze tradizionali. Portalegre attrae il turismo principalmente attraverso la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10115,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[339],"tags":[],"class_list":["post-10120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regioni-del-portogallo"],"acf":[],"_links":{"self":[{"href":"https:\/\/xrei.com\/it\/wp-json\/wp\/v2\/posts\/10120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xrei.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xrei.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xrei.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xrei.com\/it\/wp-json\/wp\/v2\/comments?post=10120"}],"version-history":[{"count":0,"href":"https:\/\/xrei.com\/it\/wp-json\/wp\/v2\/posts\/10120\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xrei.com\/it\/wp-json\/wp\/v2\/media\/10115"}],"wp:attachment":[{"href":"https:\/\/xrei.com\/it\/wp-json\/wp\/v2\/media?parent=10120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xrei.com\/it\/wp-json\/wp\/v2\/categories?post=10120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xrei.com\/it\/wp-json\/wp\/v2\/tags?post=10120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}